{"id":9594,"date":"2023-01-23T14:15:17","date_gmt":"2023-01-23T13:15:17","guid":{"rendered":"https:\/\/dfg.nl\/?post_type=news&#038;p=9594"},"modified":"2023-01-23T11:41:45","modified_gmt":"2023-01-23T10:41:45","slug":"dutch-flower-group-becomes-shareholder-in-nini-herburg-roses","status":"publish","type":"news","link":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/","title":{"rendered":"Dutch Flower Group becomes shareholder in Nini Herburg Roses"},"content":{"rendered":"","protected":false},"featured_media":9590,"template":"","categories":[6],"class_list":["post-9594","news","type-news","status-publish","has-post-thumbnail","hentry","category-none"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dutch Flower Group becomes shareholder in Nini Herburg Roses - Dutch Flower Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dutch Flower Group becomes shareholder in Nini Herburg Roses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Flower Group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Makinglifecolourful1999\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dfg.nl\/wp-content\/uploads\/2023\/01\/Photo-press-release-Dutch-Flower-Group-Nini-Herburg-Roses.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dfg.nl\\\/en\\\/news\\\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\\\/\",\"url\":\"https:\\\/\\\/dfg.nl\\\/en\\\/news\\\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\\\/\",\"name\":\"Dutch Flower Group becomes shareholder in Nini Herburg Roses - Dutch Flower Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dfg.nl\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dfg.nl\\\/en\\\/news\\\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dfg.nl\\\/en\\\/news\\\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dfg.nl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Photo-press-release-Dutch-Flower-Group-Nini-Herburg-Roses.jpg\",\"datePublished\":\"2023-01-23T13:15:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dfg.nl\\\/en\\\/news\\\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dfg.nl\\\/en\\\/news\\\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dfg.nl\\\/en\\\/news\\\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dfg.nl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Photo-press-release-Dutch-Flower-Group-Nini-Herburg-Roses.jpg\",\"contentUrl\":\"https:\\\/\\\/dfg.nl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Photo-press-release-Dutch-Flower-Group-Nini-Herburg-Roses.jpg\",\"width\":1000,\"height\":667,\"caption\":\"DFG fotografie 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dfg.nl\\\/en\\\/news\\\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dfg.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dutch Flower Group becomes shareholder in Nini Herburg Roses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dfg.nl\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/dfg.nl\\\/nl\\\/\",\"name\":\"Dutch Flower Group\",\"description\":\"Making life colourful\",\"publisher\":{\"@id\":\"https:\\\/\\\/dfg.nl\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dfg.nl\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dfg.nl\\\/nl\\\/#organization\",\"name\":\"Dutch Flower Group\",\"url\":\"https:\\\/\\\/dfg.nl\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dfg.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dfg.nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/dfg-logo-new.png\",\"contentUrl\":\"https:\\\/\\\/dfg.nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/dfg-logo-new.png\",\"width\":351,\"height\":160,\"caption\":\"Dutch Flower Group\"},\"image\":{\"@id\":\"https:\\\/\\\/dfg.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Makinglifecolourful1999\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dutch-flower-group-b-v-\\\/posts\\\/?feedView=all\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dutch Flower Group becomes shareholder in Nini Herburg Roses - Dutch Flower Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/","og_locale":"en_US","og_type":"article","og_title":"Dutch Flower Group becomes shareholder in Nini Herburg Roses","og_url":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/","og_site_name":"Dutch Flower Group","article_publisher":"https:\/\/www.facebook.com\/Makinglifecolourful1999\/","og_image":[{"width":1000,"height":667,"url":"https:\/\/dfg.nl\/wp-content\/uploads\/2023\/01\/Photo-press-release-Dutch-Flower-Group-Nini-Herburg-Roses.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/","url":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/","name":"Dutch Flower Group becomes shareholder in Nini Herburg Roses - Dutch Flower Group","isPartOf":{"@id":"https:\/\/dfg.nl\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/#primaryimage"},"image":{"@id":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/#primaryimage"},"thumbnailUrl":"https:\/\/dfg.nl\/wp-content\/uploads\/2023\/01\/Photo-press-release-Dutch-Flower-Group-Nini-Herburg-Roses.jpg","datePublished":"2023-01-23T13:15:17+00:00","breadcrumb":{"@id":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/#primaryimage","url":"https:\/\/dfg.nl\/wp-content\/uploads\/2023\/01\/Photo-press-release-Dutch-Flower-Group-Nini-Herburg-Roses.jpg","contentUrl":"https:\/\/dfg.nl\/wp-content\/uploads\/2023\/01\/Photo-press-release-Dutch-Flower-Group-Nini-Herburg-Roses.jpg","width":1000,"height":667,"caption":"DFG fotografie 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/dfg.nl\/en\/news\/dutch-flower-group-becomes-shareholder-in-nini-herburg-roses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dfg.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Dutch Flower Group becomes shareholder in Nini Herburg Roses"}]},{"@type":"WebSite","@id":"https:\/\/dfg.nl\/nl\/#website","url":"https:\/\/dfg.nl\/nl\/","name":"Dutch Flower Group","description":"Making life colourful","publisher":{"@id":"https:\/\/dfg.nl\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dfg.nl\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dfg.nl\/nl\/#organization","name":"Dutch Flower Group","url":"https:\/\/dfg.nl\/nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dfg.nl\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/dfg.nl\/wp-content\/uploads\/2023\/11\/dfg-logo-new.png","contentUrl":"https:\/\/dfg.nl\/wp-content\/uploads\/2023\/11\/dfg-logo-new.png","width":351,"height":160,"caption":"Dutch Flower Group"},"image":{"@id":"https:\/\/dfg.nl\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Makinglifecolourful1999\/","https:\/\/www.linkedin.com\/company\/dutch-flower-group-b-v-\/posts\/?feedView=all"]}]}},"_links":{"self":[{"href":"https:\/\/dfg.nl\/en\/wp-json\/wp\/v2\/news\/9594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dfg.nl\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/dfg.nl\/en\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":2,"href":"https:\/\/dfg.nl\/en\/wp-json\/wp\/v2\/news\/9594\/revisions"}],"predecessor-version":[{"id":9596,"href":"https:\/\/dfg.nl\/en\/wp-json\/wp\/v2\/news\/9594\/revisions\/9596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dfg.nl\/en\/wp-json\/wp\/v2\/media\/9590"}],"wp:attachment":[{"href":"https:\/\/dfg.nl\/en\/wp-json\/wp\/v2\/media?parent=9594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dfg.nl\/en\/wp-json\/wp\/v2\/categories?post=9594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}